{"id":17127,"date":"2025-07-09T11:44:12","date_gmt":"2025-07-09T09:44:12","guid":{"rendered":"https:\/\/www.virteem.fr\/?post_type=portfolio&#038;p=17127"},"modified":"2025-09-08T17:16:23","modified_gmt":"2025-09-08T15:16:23","slug":"comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle","status":"publish","type":"portfolio","link":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/","title":{"rendered":"Comment Kronenbourg a-t-elle transform\u00e9 une contrainte r\u00e9glementaire en un outil p\u00e9dagogique innovant gr\u00e2ce \u00e0 la visite virtuelle ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17127\" class=\"elementor elementor-17127\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d84fbdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d84fbdf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eef3d86\" data-id=\"eef3d86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7d8ee7 grve-elementor-align-center elementor-widget elementor-widget-impeka_title\" data-id=\"d7d8ee7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"grve-element grve-title grve-h2\"><span>Comment Kronenbourg a-t-elle transform\u00e9 une contrainte r\u00e9glementaire en un outil p\u00e9dagogique innovant gr\u00e2ce \u00e0 la visite virtuelle ?<br><\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ecc02a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ecc02a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-81e8abb\" data-id=\"81e8abb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d7c339 elementor-widget elementor-widget-text-editor\" data-id=\"9d7c339\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sur un site industriel, la <strong>s\u00e9curit\u00e9<\/strong> n\u2019est pas une option : c\u2019est une exigence permanente. Consciente des<strong> risques multiples<\/strong> li\u00e9s \u00e0 la nature de ses installations, Kronenbourg place la <strong>pr\u00e9vention<\/strong> au coeur de sa culture d\u2019entreprise. Cette vigilance s\u2019\u00e9tend \u00e0 tous ceux qui entrent sur le site, qu\u2019ils soient salari\u00e9s ou prestataires ext\u00e9rieurs. Pour garantir un niveau d\u2019information homog\u00e8ne et r\u00e9duire tout risque d\u00e8s l\u2019arriv\u00e9e, l\u2019entreprise a fait appel \u00e0 Virteem afin de concevoir une <strong>visite virtuelle immersive<\/strong>.<\/p><p><strong>On d\u00e9nombre plus de 3877 vues en moins de 6 mois et une dur\u00e9e moyenne de session de 15 min 54.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-ed81f44\" data-id=\"ed81f44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-459b18c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"459b18c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ee87567\" data-id=\"ee87567\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5ec243 grve-elementor-align-center elementor-widget elementor-widget-impeka_icon_box\" data-id=\"f5ec243\" data-element_type=\"widget\" data-e-type=\"widget\" axa=\"\" data-widget_type=\"impeka_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"grve-element grve-box-icon grve-small grve-top-icon\"><div class=\"grve-wrapper-icon\" style=\"\"><div class=\"grve-elementor-svg-icon grve-box-icon grve-text-primary-1\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"a\" viewBox=\"0 0 200 200\"><defs><style>.f{fill:url(#e);}.g{fill:url(#d);}.h{fill:url(#c);}.i{fill:url(#b);}<\/style><linearGradient id=\"b\" x1=\"103.29\" y1=\"146.77\" x2=\"81.32\" y2=\"168.74\" gradientTransform=\"matrix(1, 0, 0, 1, 0, 0)\" gradientUnits=\"userSpaceOnUse\"><stop offset=\"0\" stop-color=\"#6bbdfd\"><\/stop><stop offset=\".08\" stop-color=\"#68b8fc\"><\/stop><stop offset=\".18\" stop-color=\"#60aafc\"><\/stop><stop offset=\".28\" stop-color=\"#5393fc\"><\/stop><stop offset=\".39\" stop-color=\"#4173fb\"><\/stop><stop offset=\".5\" stop-color=\"#2a4afa\"><\/stop><stop offset=\".6\" stop-color=\"#101cfa\"><\/stop><stop offset=\"1\" stop-color=\"#12127f\"><\/stop><\/linearGradient><linearGradient id=\"c\" x1=\"182.56\" y1=\"107.15\" x2=\"113.29\" y2=\"176.42\" xlink:href=\"#b\"><\/linearGradient><linearGradient id=\"d\" x1=\"128.17\" y1=\"66.48\" x2=\"56.93\" y2=\"137.71\" xlink:href=\"#b\"><\/linearGradient><linearGradient id=\"e\" x1=\"136.08\" y1=\"19.15\" x2=\"-4.47\" y2=\"159.7\" xlink:href=\"#b\"><\/linearGradient><\/defs><g><path class=\"i\" d=\"M90.71,174.02c-5.15,0-9.81-4.29-11.88-11.11-1.47-4.3-.58-9.06,2.33-12.55,.95-1.29,2.4-2.11,4-2.26,3.24-.16,6.09,2.1,6.66,5.29,.5,2.79-1.33,5.46-4.11,6l2.33,7.03c6.2-1.74,10.1-7.86,9.07-14.22-.41-2.52-1.5-4.78-3.05-6.62l4.88-1.16c1.72,3.03,2.72,6.81,2.72,11.08,0,10.03-5.92,18.51-12.96,18.51Z\"><\/path><path class=\"h\" d=\"M188.04,151.99l-80.67,18.51c2.49-4.6,3.76-9.76,3.7-14.99,.31-8.17-3.09-16.03-9.26-21.4l83.78-19.14c7.96,.26,14.4,8.48,14.4,18.51,0,11.11-3,15.51-11.96,18.51Z\"><\/path><\/g><path class=\"g\" d=\"M92.56,121.91l-61.76-10.33,9.48-28.51c2.15-2.15,14.66-13,52.28-13s50.2,11.11,52.24,13.03l9.52,28.51-61.75,10.29Z\"><\/path><path class=\"f\" d=\"M92.56,25.98L5.52,62.67l5.59,2.54v64.58c-6.38,1.65-11.11,7.43-11.11,14.32v18.51c0,2.04,1.66,3.7,3.7,3.7H25.92c2.04,0,3.7-1.66,3.7-3.7v-18.51c0-6.9-4.72-12.68-11.11-14.32v-61.21l17.88,8.14c5.26-4.51,20.58-13.98,56.21-13.98,42.14,0,55.86,13.24,58.14,15.86l28.86-15.93L92.56,25.98Z\"><\/path><\/svg><\/div><\/div><div class=\"grve-box-content\"><h3 class=\"grve-box-title grve-h6 grve-text-primary-1\">Secteur d'activit\u00e9<\/h3><p class=\"\">Industrie<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dad5d7d\" data-id=\"dad5d7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e6e6f5 grve-elementor-align-center elementor-widget elementor-widget-impeka_icon_box\" data-id=\"6e6e6f5\" data-element_type=\"widget\" data-e-type=\"widget\" axa=\"\" data-widget_type=\"impeka_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"grve-element grve-box-icon grve-small grve-top-icon\"><div class=\"grve-wrapper-icon\" style=\"\"><div class=\"grve-elementor-svg-icon grve-box-icon grve-text-primary-1\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"a\" viewBox=\"0 0 200 200\"><defs><style>.e{fill:url(#d);}.f{fill:url(#c);}.g{fill:url(#b);}<\/style><linearGradient id=\"b\" x1=\"129.78\" y1=\"152.45\" x2=\"70.21\" y2=\"212.02\" gradientTransform=\"matrix(1, 0, 0, 1, 0, 0)\" gradientUnits=\"userSpaceOnUse\"><stop offset=\"0\" stop-color=\"#6bbdfd\"><\/stop><stop offset=\".08\" stop-color=\"#68b8fc\"><\/stop><stop offset=\".18\" stop-color=\"#60aafc\"><\/stop><stop offset=\".28\" stop-color=\"#5393fc\"><\/stop><stop offset=\".39\" stop-color=\"#4173fb\"><\/stop><stop offset=\".5\" stop-color=\"#2a4afa\"><\/stop><stop offset=\".6\" stop-color=\"#101cfa\"><\/stop><stop offset=\"1\" stop-color=\"#12127f\"><\/stop><\/linearGradient><linearGradient id=\"c\" x1=\"113\" y1=\"51.23\" x2=\"86.99\" y2=\"77.24\" xlink:href=\"#b\"><\/linearGradient><linearGradient id=\"d\" x1=\"148.38\" y1=\"33.28\" x2=\"51.59\" y2=\"130.06\" xlink:href=\"#b\"><\/linearGradient><\/defs><path class=\"g\" d=\"M104.35,172.57c-.2,1.65-.33,3.33-.33,5.02,0,2.24-1.81,4.06-4.06,4.06s-3.99-1.81-3.99-4.06c0-1.65-.13-3.33-.33-5.02-32.81,.46-52.48,6.17-55.19,9.67,2.84,3.63,24.06,9.71,59.51,9.71s56.74-6.04,59.58-9.71c-2.71-3.5-22.38-9.21-55.19-9.67Z\"><\/path><path class=\"f\" d=\"M99.97,82.62c10.2,0,18.45-8.25,18.45-18.39s-8.25-18.39-18.45-18.39-18.39,8.25-18.39,18.39,8.25,18.35,18.39,18.39Z\"><\/path><path class=\"e\" d=\"M59.03,102.59c2.57,2.08,40.97,39.27,40.93,75.85,.03-36.58,38.35-73.74,41-75.82,9.8-10.46,15.15-24.06,15.15-38.39,0-30.96-25.19-56.15-56.15-56.15s-56.08,25.19-56.08,56.15c0,14.36,5.35,27.92,15.15,38.35h0ZM99.96,37.8c14.66,0,26.51,11.85,26.51,26.44s-11.88,26.44-26.51,26.44-26.44-11.88-26.44-26.44,11.88-26.44,26.44-26.44Z\"><\/path><\/svg><\/div><\/div><div class=\"grve-box-content\"><h3 class=\"grve-box-title grve-h6 grve-text-primary-1\">Port\u00e9e<\/h3><p class=\"\">Internationale<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9a640a6\" data-id=\"9a640a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40d9118 grve-elementor-align-center elementor-widget elementor-widget-impeka_icon_box\" data-id=\"40d9118\" data-element_type=\"widget\" data-e-type=\"widget\" axa=\"\" data-widget_type=\"impeka_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"grve-element grve-box-icon grve-small grve-top-icon\"><div class=\"grve-wrapper-icon\" style=\"\"><div class=\"grve-elementor-svg-icon grve-box-icon grve-text-primary-1\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"a\" viewBox=\"0 0 200 200\"><defs><style>.c{fill:url(#b);}<\/style><linearGradient id=\"b\" x1=\"170.69\" y1=\"29.27\" x2=\"29.27\" y2=\"170.69\" gradientTransform=\"matrix(1, 0, 0, 1, 0, 0)\" gradientUnits=\"userSpaceOnUse\"><stop offset=\"0\" stop-color=\"#6bbdfd\"><\/stop><stop offset=\".08\" stop-color=\"#68b8fc\"><\/stop><stop offset=\".18\" stop-color=\"#60aafc\"><\/stop><stop offset=\".28\" stop-color=\"#5393fc\"><\/stop><stop offset=\".39\" stop-color=\"#4173fb\"><\/stop><stop offset=\".5\" stop-color=\"#2a4afa\"><\/stop><stop offset=\".6\" stop-color=\"#101cfa\"><\/stop><stop offset=\"1\" stop-color=\"#12127f\"><\/stop><\/linearGradient><\/defs><path class=\"c\" d=\"M170.71,29.29C151.96,10.54,126.52,0,100,0S48.04,10.54,29.29,29.29C10.54,48.04,0,73.48,0,100s10.54,51.96,29.29,70.71c18.76,18.75,44.19,29.29,70.71,29.29h0c26.51-.03,51.93-10.57,70.68-29.32,18.75-18.75,29.29-44.16,29.32-70.68,0-26.52-10.54-51.96-29.29-70.71Zm11.43,70.71c0,1.97-1.6,3.57-3.57,3.57h-7.14c-.95,0-1.86-.38-2.53-1.05s-1.05-1.58-1.05-2.53c0-1.97,1.6-3.57,3.57-3.57h7.14c1.97,0,3.57,1.6,3.57,3.57Zm-22.07-38.81l6.19-3.57c1.71-.97,3.88-.38,4.86,1.32,.98,1.7,.41,3.87-1.29,4.87l-6.19,3.57c-.54,.31-1.16,.48-1.79,.48h0c-1.62,0-3.03-1.09-3.45-2.65-.42-1.56,.26-3.21,1.66-4.02Zm-1.33,72.73c.48-.82,1.26-1.43,2.18-1.67,.92-.24,1.9-.11,2.72,.37l6.19,3.57c1.69,.99,2.27,3.17,1.29,4.87-.98,1.7-3.15,2.29-4.86,1.32l-6.19-3.57h0c-.83-.47-1.43-1.25-1.68-2.17-.25-.92-.12-1.9,.35-2.72Zm-56.91-30.86c-1.1,.66-2.48,.68-3.6,.05-1.12-.63-1.81-1.82-1.81-3.11V39.28c0-1.97,1.6-3.57,3.57-3.57s3.57,1.6,3.57,3.57v54.41l30.3-18.18c1.69-1.02,3.88-.47,4.9,1.22h0c1.02,1.69,.47,3.88-1.22,4.9l-35.71,21.43Zm1.73,68.37v7.14c0,1.97-1.6,3.57-3.57,3.57s-3.57-1.6-3.57-3.57v-7.14c0-1.97,1.6-3.57,3.57-3.57s3.57,1.6,3.57,3.57Zm-7.14-142.86v-7.14c0-1.97,1.6-3.57,3.57-3.57s3.57,1.6,3.57,3.57v7.14c0,.95-.38,1.86-1.05,2.53s-1.58,1.05-2.53,1.05-1.86-.38-2.53-1.05-1.05-1.58-1.05-2.53Zm35.82,132.35c.24-.92,.84-1.7,1.67-2.18,.82-.48,1.8-.6,2.72-.35,.92,.25,1.7,.85,2.17,1.68l3.57,6.19c.97,1.71,.38,3.88-1.32,4.86-1.7,.98-3.87,.41-4.87-1.29l-3.57-6.19c-.48-.82-.62-1.8-.37-2.72Zm.37-124.57l3.57-6.19c.99-1.69,3.17-2.27,4.87-1.29,1.7,.98,2.29,3.15,1.32,4.86l-3.57,6.19c-.99,1.71-3.17,2.29-4.88,1.31h0c-1.71-.99-2.29-3.17-1.31-4.88Zm33.04,129.31c-17.42,17.41-41.03,27.2-65.66,27.2s-48.25-9.78-65.66-27.2C16.93,148.25,7.14,124.63,7.14,100s9.78-48.25,27.2-65.66C51.76,16.93,75.37,7.14,100,7.14c1.97,0,3.57,1.6,3.57,3.57s-1.6,3.57-3.57,3.57c-22.73,0-44.53,9.03-60.61,25.11-16.07,16.07-25.11,37.88-25.11,60.61s9.03,44.53,25.11,60.61c16.07,16.07,37.88,25.11,60.61,25.11s44.53-9.03,60.61-25.11c16.07-16.07,25.11-37.88,25.11-60.61,0-1.97,1.6-3.57,3.57-3.57h0c.95,0,1.86,.38,2.53,1.05,.67,.67,1.05,1.58,1.05,2.53,0,24.63-9.78,48.25-27.2,65.66ZM67.75,39.07c-.24,.92-.84,1.7-1.67,2.18-.82,.48-1.8,.6-2.72,.35-.92-.25-1.7-.85-2.17-1.68l-3.57-6.19c-.97-1.71-.38-3.88,1.32-4.86,1.7-.98,3.87-.41,4.87,1.29l3.57,6.19h0c.48,.82,.62,1.8,.37,2.72Zm-.37,124.57l-3.57,6.19c-.47,.83-1.25,1.43-2.17,1.68-.92,.25-1.9,.12-2.72-.35-.82-.48-1.43-1.26-1.67-2.18-.24-.92-.11-1.9,.37-2.72l3.57-6.19c.99-1.71,3.17-2.29,4.88-1.31h0c1.71,.99,2.29,3.17,1.31,4.88Zm-27.45-24.83l-6.19,3.57c-.54,.31-1.16,.48-1.79,.48-1.62,0-3.03-1.09-3.45-2.65-.42-1.56,.26-3.21,1.66-4.02h0l6.19-3.57c.82-.48,1.8-.62,2.72-.37,.92,.24,1.7,.84,2.18,1.67,.48,.82,.6,1.8,.35,2.72-.25,.92-.85,1.7-1.68,2.17h0Zm-11.36-42.38c.95,0,1.86,.38,2.53,1.05,.67,.67,1.05,1.58,1.05,2.53s-.38,1.86-1.05,2.53c-.67,.67-1.58,1.05-2.53,1.05h-7.14c-1.97,0-3.57-1.6-3.57-3.57s1.6-3.57,3.57-3.57h7.14Zm.31-37.49c.98-1.7,3.15-2.29,4.86-1.32l6.19,3.57h0c.83,.47,1.43,1.25,1.68,2.17,.25,.92,.12,1.9-.35,2.72-.48,.82-1.26,1.43-2.18,1.67-.92,.24-1.9,.11-2.72-.37l-6.19-3.57c-1.69-.99-2.27-3.17-1.29-4.87Z\"><\/path><\/svg><\/div><\/div><div class=\"grve-box-content\"><h3 class=\"grve-box-title grve-h6 grve-text-primary-1\">Temps de d\u00e9ploiement<\/h3><p class=\"\">2 mois<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78f8ab7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"78f8ab7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d1cd6c\" data-id=\"3d1cd6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13b492a grve-elementor-align-right elementor-fixed e-transform elementor-invisible elementor-widget elementor-widget-impeka_button\" data-id=\"13b492a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;,&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-90,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"impeka_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"grve-element\"><a href=\"https:\/\/www.virteem.fr\/contact\/\" target=\"_blank\" class=\"grve-btn grve-round grve-bg-primary-1 grve-border-primary-1 grve-bg-hover-black grve-border-hover-black grve-text-white grve-text-hover-white grve-shadow-large grve-btn-small grve-with-svg-icon-arrow-1\">\r\n\t\t<div class=\"grve-btn-inner\">\r\n\t\t<span>Demander une d\u00e9mo<\/span>\r\n\t\t\t\t\t\t\t<div class=\"grve-btn-svg-icon\">\r\n\t\t\t\t\t\t<svg width=\"12px\" height=\"12px\" viewBox=\"0 0 12 12\">\r\n\t\t\t\t<polygon points=\"3.6 0 10 6 3.6 12 2 10.5 6.8 6 2 1.5\"><\/polygon>\r\n\t\t\t<\/svg>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c2c013 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c2c013\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc7d5db\" data-id=\"bc7d5db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-daf43e8 grve-elementor-align-left elementor-widget elementor-widget-impeka_title\" data-id=\"daf43e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"grve-element grve-title grve-h3 grve-text-primary-1\"><span>\u00c0 propos<br><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db7ebef elementor-widget elementor-widget-text-editor\" data-id=\"db7ebef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cr\u00e9\u00e9e en 1664, <strong>Kronenbourg est la plus ancienne brasserie fran\u00e7aise<\/strong> encore en activit\u00e9. Aujourd\u2019hui install\u00e9e \u00e0 Obernai, en Alsace, elle y exploite la plus grande brasserie de France. Plus qu\u2019un site de production, c\u2019est un v\u00e9ritable lieu de savoir-faire et d\u2019engagement. Avec plus de mille collaborateurs passionn\u00e9s, <strong>Kronenbourg place l\u2019humain et la s\u00e9curit\u00e9 au coeur de son fonctionnement<\/strong>, en cultivant une d\u00e9marche de pr\u00e9vention active pour prot\u00e9ger de mani\u00e8re durable ses \u00e9quipes et ses partenaires ext\u00e9rieurs. Cet engagement se traduit par des actions concr\u00e8tes, en particulier dans le domaine de la formation \u00e0 la s\u00e9curit\u00e9. Consciente que la sensibilisation aux risques doit \u00eatre claire, accessible et impactante, <strong>l\u2019entreprise mise sur des outils num\u00e9riques innovants pour renforcer l\u2019efficacit\u00e9 de ses d\u00e9marches<\/strong>. Kronenbourg s\u2019engage ainsi dans une<strong> d\u00e9marche proactive<\/strong>, ancr\u00e9e dans la r\u00e9alit\u00e9 du terrain et qui permet de mieux appr\u00e9hender la question de la s\u00e9curit\u00e9 sur le site.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ec42d8 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ec42d8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f08de2\" data-id=\"3f08de2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e011d7 grve-elementor-align-left elementor-invisible elementor-widget elementor-widget-impeka_slogan\" data-id=\"1e011d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"impeka_slogan.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div data-animation=\"fade-in-up\" data-delay=\"200\" data-duration=\"normal\" class=\"grve-element grve-slogan grve-animated-item\"><h2 class=\"grve-slogan-title grve-h2 grve-text-primary-1\" style=\"\"><span>Le challenge<\/span><\/h2><p class=\"\">Le site Kronenbourg, par sa nature\nindustrielle, pr\u00e9sente une diversit\u00e9\nde risques bien r\u00e9els : manipulation\nde produits chimiques, machines\nen mouvement, travail en\nhauteur, pr\u00e9sence de CO2 li\u00e9 \u00e0 la\nfermentation, sols glissants, bruit,\nmanutention... Face \u00e0 ces enjeux,\nil \u00e9tait imp\u00e9ratif de concevoir\nune formation s\u00e9curit\u00e9 \u00e0 la fois\ncompl\u00e8te, accessible \u00e0 distance,\net adapt\u00e9e \u00e0 tous les publics,\nnotamment les int\u00e9rimaires et les\nprestataires ext\u00e9rieurs.\nL\u2019objectif : transmettre les r\u00e8gles\nessentielles \u00e0 conna\u00eetre avant toute\nintervention sur site en s\u2019assurant\nqu\u2019elles soient r\u00e9ellement\ncomprises, int\u00e9gr\u00e9es et appliqu\u00e9es.\n<\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da74e1f\" data-id=\"da74e1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-321d6fe grve-elementor-align-left elementor-invisible elementor-widget elementor-widget-impeka_image_single\" data-id=\"321d6fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"impeka_image_single.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div data-animation=\"fade-in\" data-delay=\"400\" data-duration=\"normal\" class=\"grve-element grve-image grve-animated-item\">\r\n\t<div class=\"grve-image-item\">\r\n\t\t\r\n\r\n<div class=\"grve-image-wrapper grve-radius-10 grve-none\">\r\n\t\t<div class=\"grve-thumbnail-wrapper\"  style=\"width: 0px;\"><div class=\"grve-thumbnail\"  style=\"padding-top: 0%;\"><\/div><\/div>\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54b4011 elementor-widget elementor-widget-image\" data-id=\"54b4011\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"463\" src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10-1024x463.png\" class=\"attachment-large size-large wp-image-17136\" alt=\"Comment Kronenbourg a-t-elle transform\u00e9 une contrainte r\u00e9glementaire en un outil p\u00e9dagogique innovant gr\u00e2ce \u00e0 la visite virtuelle ?\" srcset=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10-1024x463.png 1024w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10-300x136.png 300w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10-768x347.png 768w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10-1536x694.png 1536w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10-18x8.png 18w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10-500x226.png 500w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10-800x362.png 800w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10-1280x579.png 1280w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/10.png 1918w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fe57b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fe57b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56101a1\" data-id=\"56101a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3cdd81 grve-elementor-align-center elementor-invisible elementor-widget elementor-widget-impeka_title\" data-id=\"d3cdd81\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"impeka_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"grve-element grve-title grve-h3 grve-text-primary-1 grve-subtitle\"><span><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-420ab4e elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"420ab4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:43,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" kronenbourg=\"\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-Caroussel-3.png\" alt=\"Ext\u00e9rieur b\u00e2timent Mercure Kronenbourg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-Caroussel-4.png\" alt=\"Station d&#039;\u00e9puration Kronenbourg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-Caroussel-2.png\" alt=\"S\u00e9curit\u00e9 Kronenbourg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-Caroussel-5.png\" alt=\"Salle de contr\u00f4le Kronenbourg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-Caroussel-1.png\" alt=\"Local produits chimiques\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-Caroussel.png\" alt=\"Chasse aux risques\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cd90f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cd90f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-446bd82\" data-id=\"446bd82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a917b7b grve-elementor-align-center elementor-invisible elementor-widget elementor-widget-impeka_title\" data-id=\"a917b7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"impeka_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"grve-element grve-title grve-h2\"><span><h2>La solution<\/h2><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cb26f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cb26f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca8c71c\" data-id=\"ca8c71c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a00946f elementor-widget elementor-widget-text-editor\" data-id=\"a00946f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Virteem a con\u00e7u une<strong> visite virtuelle interactive et immersive<\/strong> du site de Kronenbourg. Gr\u00e2ce \u00e0 l\u2019int\u00e9gration de vues drones, de vid\u00e9os sur fond vert, d\u2019un <strong>QCM<\/strong> final et d\u2019une \u201c<strong>Chasse aux risques<\/strong>\u201d, le parcours propose une exploration guid\u00e9e du site. Le visiteur avance \u00e9tape par \u00e9tape. Chaque contenu devant \u00eatre consult\u00e9 et valid\u00e9 pour poursuivre la visite, cela permet de favoriser une r\u00e9elle <strong>appropriation des consignes de s\u00e9curit\u00e9<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0e7fec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0e7fec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07c3744\" data-id=\"07c3744\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-894bca5 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"894bca5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8d036e0\" data-id=\"8d036e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4971589 grve-elementor-align-left elementor-widget elementor-widget-impeka_icon\" data-id=\"4971589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"grve-element grve-single-icon grve-medium\"><div class=\"grve-wrapper-icon grve-text-primary-1\"><i aria-hidden=\"true\" class=\"fas fa-stream\"><\/i><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ccc7b9 grve-elementor-align-left elementor-widget elementor-widget-impeka_title\" data-id=\"0ccc7b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"grve-element grve-title grve-h3\"><span><span style=\"font-weight: 400;\">Le projet :<\/span><br><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-309deae elementor-widget elementor-widget-text-editor\" data-id=\"309deae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<article class=\"w-full text-token-text-primary\" dir=\"auto\" data-testid=\"conversation-turn-22\" data-scroll-anchor=\"true\"><div class=\"text-base my-auto mx-auto py-5 px-6\"><div class=\"mx-auto flex flex-1 text-base gap-4 md:gap-5 lg:gap-6 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group\/turn-messages focus-visible:outline-none\" tabindex=\"-1\"><div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn @xs\/thread:px-0 @sm\/thread:px-1.5 @md\/thread:px-4\"><div class=\"relative flex-col gap-1 md:gap-3\"><div class=\"flex max-w-full flex-col flex-grow\"><div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 whitespace-normal break-words text-start [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"0a82ce48-4270-46a5-b778-ae2213ce2e46\" data-message-model-slug=\"gpt-4o-mini\"><div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><article class=\"text-token-text-primary w-full\" dir=\"auto\" data-testid=\"conversation-turn-10\" data-scroll-anchor=\"true\"><div class=\"text-base my-auto mx-auto py-5 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[70rem]:[--thread-content-margin:--spacing(12)] px-(--thread-content-margin)\"><div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto flex max-w-(--thread-content-max-width) flex-1 text-base gap-4 md:gap-5 lg:gap-6 group\/turn-messages focus-visible:outline-hidden\" tabindex=\"-1\"><div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\"><div class=\"relative flex-col gap-1 md:gap-3\"><div class=\"flex max-w-full flex-col grow\"><div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"4e5ba87d-8362-439a-80bc-07738082633c\" data-message-model-slug=\"gpt-4o-mini\"><div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\"><div class=\"markdown prose dark:prose-invert w-full break-words light\"><article class=\"text-token-text-primary w-full\" dir=\"auto\" data-testid=\"conversation-turn-10\" data-scroll-anchor=\"true\"><div class=\"text-base my-auto mx-auto py-5 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\"><div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto flex max-w-(--thread-content-max-width) flex-1 text-base gap-4 md:gap-5 lg:gap-6 group\/turn-messages focus-visible:outline-hidden\" tabindex=\"-1\"><div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\"><div class=\"relative flex-col gap-1 md:gap-3\"><div class=\"flex max-w-full flex-col grow\"><div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"8fa7ad75-3d2d-4a23-a280-5ddef0ecd833\" data-message-model-slug=\"gpt-4o\"><div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\"><div class=\"markdown prose dark:prose-invert w-full break-words light\"><p data-start=\"0\" data-end=\"635\" data-is-last-node=\"\" data-is-only-node=\"\">Depuis son d\u00e9ploiement, la visite virtuelle a transform\u00e9 la formation s\u00e9curit\u00e9 chez Kronenbourg. Elle offre un parcours clair, homog\u00e8ne et accessible \u00e0 tous. Ainsi, chacun peut se former \u00e0 distance, sans contrainte de lieu ni d\u2019horaire. De plus, le format immersif capte mieux l\u2019attention et renforce la m\u00e9morisation. L\u2019outil a aussi \u00e9t\u00e9 tr\u00e8s bien accueilli en interne. L\u2019\u00e9quipe s\u00e9curit\u00e9 le juge moderne, p\u00e9dagogique et engageant. Enfin, les utilisateurs appr\u00e9cient sa simplicit\u00e9 et la clart\u00e9 des contenus.\u00a0<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/article>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cb7921e\" data-id=\"cb7921e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d347a65 grve-elementor-align-left elementor-widget elementor-widget-impeka_icon\" data-id=\"d347a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"grve-element grve-single-icon grve-medium\"><div class=\"grve-wrapper-icon grve-text-primary-1\"><i aria-hidden=\"true\" class=\"fas fa-stream\"><\/i><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-352f645 grve-elementor-align-left elementor-widget elementor-widget-impeka_title\" data-id=\"352f645\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"grve-element grve-title grve-h3\"><span><span style=\"font-weight: 400;\">Contenu de la visite virtuelle :<\/span><br><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d99fae7 elementor-widget elementor-widget-text-editor\" data-id=\"d99fae7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Une visite virtuelle immersive 360\u00b0<\/li><li>Une traduction int\u00e9grale en anglais et allemand\u00a0<\/li><li>Des points d&rsquo;information cliquables<\/li><li>L&rsquo;int\u00e9gration de vid\u00e9os fond vert<\/li><li>L&rsquo;int\u00e9gration d&rsquo;une chasse aux risques<\/li><li>un QCM d&rsquo;\u00e9valuation<\/li><li>Des fonctionnalit\u00e9s Lego<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-11adabf\" data-id=\"11adabf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d40bba3 grve-elementor-align-left elementor-widget elementor-widget-impeka_icon\" data-id=\"d40bba3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"grve-element grve-single-icon grve-medium\"><div class=\"grve-wrapper-icon grve-text-primary-1\"><i aria-hidden=\"true\" class=\"fas fa-stream\"><\/i><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72dd816 grve-elementor-align-left elementor-widget elementor-widget-impeka_title\" data-id=\"72dd816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"grve-element grve-title grve-h3\"><span><span style=\"font-weight: 400;\">Un outil durable gr\u00e2ce au Back-office :<\/span><br><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-756279a elementor-widget elementor-widget-text-editor\" data-id=\"756279a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Avec Virteem, nos solutions sont reli\u00e9es \u00e0 un back-office exclusif pour chaque client. L&rsquo;objectif est que nos clients puissent faire de leur solution un outil durable. L&rsquo;\u00e9quipe de Kronenbourg a ainsi la possibilit\u00e9 de modifier les points de contenus de la visite en fonction de son actualit\u00e9 et de ses objectifs. Les back-office sont g\u00e9r\u00e9s en autonomie par les \u00e9quipes, que ce soit en termes de vid\u00e9os, PDF ou photos. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-eccad7b grve-elementor-align-center elementor-widget elementor-widget-impeka_button\" data-id=\"eccad7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"grve-element\"><a href=\"https:\/\/www.virteem.fr\/contact\/\" class=\"grve-btn-text grve-btn-line grve-line-left grve-text-primary-1 grve-text-hover-primary-1 grve-btn-medium\">\r\n\t\t<div class=\"grve-btn-inner\">\r\n\t\t<span>Demander une d\u00e9mo<\/span>\r\n\t\t\t<span class=\"grve-line grve-bg-primary-1\"><\/span>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d99d709 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"d99d709\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9e04716\" data-id=\"9e04716\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22c0dec grve-elementor-align-left elementor-widget elementor-widget-impeka_title\" data-id=\"22c0dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"grve-element grve-title grve-h3\"><span>Pour conna\u00eetre les r\u00e9sultats, t\u00e9l\u00e9chargez l\u2019\u00e9tude de cas.\u00a0<br><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3e0c2b elementor-widget elementor-widget-text-editor\" data-id=\"e3e0c2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Taux d&rsquo;engagement, nombre de pages vues, nombre d\u2019utilisateurs \u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d2041c2\" data-id=\"d2041c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c831b1 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"0c831b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Comment Kronenbourg a-t-elle transform\u00e9 une contrainte r\u00e9glementaire en un outil p\u00e9dagogique innovant gr\u00e2ce \u00e0 la visite virtuelle ?\" aria-label=\"Comment Kronenbourg a-t-elle transform\u00e9 une contrainte r\u00e9glementaire en un outil p\u00e9dagogique innovant gr\u00e2ce \u00e0 la visite virtuelle ?\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"17127\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"0c831b1\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Etude de cas - Kronenbourg\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"17127\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-nom elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-nom\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNom Pr\u00e9nom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[nom]\" id=\"form-field-nom\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_686d78f elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_686d78f\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tT\u00e9l\u00e9phone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_686d78f]\" id=\"form-field-field_686d78f\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"T\u00e9l\u00e9phone\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_3bc9f4a elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3bc9f4a\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tSoci\u00e9t\u00e9\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_3bc9f4a]\" id=\"form-field-field_3bc9f4a\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Soci\u00e9t\u00e9\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha elementor-field-group elementor-column elementor-field-group-field_6686a46 elementor-col-100\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_6686a46\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LdXKZMpAAAAAKEgSZOZAt6td_nKrbuAfBa2ThAu\" data-type=\"v2_checkbox\" data-theme=\"light\" data-size=\"normal\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm elementor-animation-grow\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7027d78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7027d78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5555e3\" data-id=\"a5555e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7126c0 elementor-widget elementor-widget-impeka_portfolio\" data-id=\"d7126c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"impeka_portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div data-display-style=\"pagination\" data-spinner=\"no\" data-columns-large-screen=\"2\" data-columns=\"2\" data-columns-tablet-landscape=\"2\" data-columns-tablet-portrait=\"2\" data-columns-mobile=\"1\" data-layout=\"fitRows\" data-gutter-size=\"30\" data-animation=\"none\" data-items-height=\"equal\" class=\"grve-element grve-portfolio grve-isotope grve-with-gap\" id=\"el-75f7f23\">\r\n\t<div class=\"grve-isotope-container\">\r\n\t\t<div class=\"grve-grid-sizer\"><\/div>\r\n\t\t<div class=\"post-20049 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-ec-ecoles portfolio_category-etude-de-cas grve-entry-item\">\r\n\t\t\t<div class=\"grve-isotope-item-inner\">\r\n\t\t\t\t<div class=\"grve-hover-item grve-thumb-mouse-move grve-hover-style-7\">\r\n\t<div data-indicator=\"plus\" data-indicator-color=\"primary-1\" class=\"grve-image-hover grve-media grve-radius-10\">\r\n\t\t\t\t<a class=\"grve-item-url\" href=\"https:\/\/www.virteem.fr\/en\/portfolio\/comment-cy-cergy-paris-universite-a-connu-une-hausse-de-24-de-frequentation-grace-a-la-jpo-virtuelle\/\"><span class=\"screen-reader-text\">Comment CY Cergy Paris Universit\u00e9 a connu une hausse de 24% de fr\u00e9quentation gr\u00e2ce \u00e0 la JPO Virtuelle ?<\/span><\/a>\r\n\t\t\t\t<div class=\"grve-thumbnail-wrapper\"><div class=\"grve-thumbnail\"  style=\"padding-top: 48.667%;\"><img decoding=\"async\" width=\"300\" height=\"146\" src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/04\/vue-generale-300x146.png\" class=\"attachment-medium size-medium grve-lazy-load lazyload\" alt=\"visite virtuelle CY\" data-column-space=\"100\" data-lazyload=\"\" data-grve-filter=\"yes\" srcset=\"https:\/\/www.virteem.fr\/wp-content\/themes\/impeka\/images\/empty\/empty.png\" data-src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/04\/vue-generale-300x146.png\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/04\/vue-generale-300x146.png 300w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/04\/vue-generale-1024x499.png 1024w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/04\/vue-generale-768x374.png 768w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/04\/vue-generale-1536x749.png 1536w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/04\/vue-generale-600x293.png 600w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/04\/vue-generale.png 1920w\" data-expand=\"1\" \/><\/div><\/div>\t\t\t\t<div class=\"grve-gradient-overlay grve-bg-overlay grve-opacity-100\"><\/div>\r\n\t\t\t\t<div class=\"grve-content\">\r\n\t\t\t<div class=\"grve-content-inner\">\r\n\t\t\t\t\t\t<h3 class=\"grve-title grve-h6 grve-text-white\"><span>Comment CY Cergy Paris Universit\u00e9 a connu une hausse de 24% de fr\u00e9quentation gr\u00e2ce \u00e0 la JPO Virtuelle ?<\/span><\/h3>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"post-20043 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-ec-ecoles portfolio_category-etude-de-cas grve-entry-item\">\r\n\t\t\t<div class=\"grve-isotope-item-inner\">\r\n\t\t\t\t<div class=\"grve-hover-item grve-thumb-mouse-move grve-hover-style-7\">\r\n\t<div data-indicator=\"plus\" data-indicator-color=\"primary-1\" class=\"grve-image-hover grve-media grve-radius-10\">\r\n\t\t\t\t<a class=\"grve-item-url\" href=\"https:\/\/www.virteem.fr\/en\/portfolio\/comment-grenoble-ecole-de-management-a-attire-des-etudiants-grace-a-la-visite-virtuelle-et-aux-vues-360-de-la-ville\/\"><span class=\"screen-reader-text\">Comment Grenoble Ecole de management a attir\u00e9 des \u00e9tudiants gr\u00e2ce \u00e0 la visite virtuelle et aux vues 360\u00b0 de la ville ?<\/span><\/a>\r\n\t\t\t\t<div class=\"grve-thumbnail-wrapper\"><div class=\"grve-thumbnail\"  style=\"padding-top: 52.667%;\"><img decoding=\"async\" width=\"300\" height=\"158\" src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/premier-pas-300x158.png\" class=\"attachment-medium size-medium grve-lazy-load lazyload\" alt=\"visite virtuelle Grenoble \u00c9cole de management\" data-column-space=\"100\" data-lazyload=\"\" data-grve-filter=\"yes\" srcset=\"https:\/\/www.virteem.fr\/wp-content\/themes\/impeka\/images\/empty\/empty.png\" data-src=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/premier-pas-300x158.png\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/premier-pas-300x158.png 300w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/premier-pas-1024x539.png 1024w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/premier-pas-768x404.png 768w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/premier-pas-1536x808.png 1536w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/premier-pas-600x316.png 600w, https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/premier-pas.png 1920w\" data-expand=\"1\" \/><\/div><\/div>\t\t\t\t<div class=\"grve-gradient-overlay grve-bg-overlay grve-opacity-100\"><\/div>\r\n\t\t\t\t<div class=\"grve-content\">\r\n\t\t\t<div class=\"grve-content-inner\">\r\n\t\t\t\t\t\t<h3 class=\"grve-title grve-h6 grve-text-white\"><span>Comment Grenoble Ecole de management a attir\u00e9 des \u00e9tudiants gr\u00e2ce \u00e0 la visite virtuelle et aux vues 360\u00b0 de la ville ?<\/span><\/h3>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Kronenbourg a transform\u00e9 une contrainte r\u00e9glementaire en outil p\u00e9dagogique innovant gr\u00e2ce \u00e0 une visite virtuelle immersive con\u00e7ue avec Virteem. R\u00e9sultat : une formation s\u00e9curit\u00e9 engageante, accessible, et parfaitement adapt\u00e9e \u00e0 tous les profils.<\/p>","protected":false},"author":3,"featured_media":18916,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Etude de cas - Kronenbourg","_seopress_titles_desc":"Kronenbourg mise sur une visite virtuelle immersive pour moderniser et renforcer la formation s\u00e9curit\u00e9 sur son site industriel.","_seopress_robots_index":"","inline_featured_image":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"portfolio_category":[48,41],"portfolio_field":[],"portfolio_tag":[],"class_list":["post-17127","portfolio","type-portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-ec-industrie","portfolio_category-etude-de-cas","grve-entry-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Etude de cas - Kronenbourg<\/title>\n<meta name=\"description\" content=\"Kronenbourg mise sur une visite virtuelle immersive pour moderniser et renforcer la formation s\u00e9curit\u00e9 sur son site industriel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Etude de cas - Kronenbourg\" \/>\n<meta property=\"og:description\" content=\"Kronenbourg mise sur une visite virtuelle immersive pour moderniser et renforcer la formation s\u00e9curit\u00e9 sur son site industriel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/\" \/>\n<meta property=\"og:site_name\" content=\"Virteem\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T15:16:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-7-1024x536.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/en\\\/portfolio\\\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\\\/\",\"url\":\"https:\\\/\\\/www.virteem.fr\\\/en\\\/portfolio\\\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\\\/\",\"name\":\"Etude de cas - Kronenbourg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/en\\\/portfolio\\\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/en\\\/portfolio\\\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.virteem.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vignette-Etude-de-cas-7.png\",\"datePublished\":\"2025-07-09T09:44:12+00:00\",\"dateModified\":\"2025-09-08T15:16:23+00:00\",\"description\":\"Kronenbourg mise sur une visite virtuelle immersive pour moderniser et renforcer la formation s\u00e9curit\u00e9 sur son site industriel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/en\\\/portfolio\\\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.virteem.fr\\\/en\\\/portfolio\\\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/en\\\/portfolio\\\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.virteem.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vignette-Etude-de-cas-7.png\",\"contentUrl\":\"https:\\\/\\\/www.virteem.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vignette-Etude-de-cas-7.png\",\"width\":1797,\"height\":940,\"caption\":\"Etude de cas - Brasseries Kronenbourg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/en\\\/portfolio\\\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.virteem.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/www.virteem.fr\\\/en\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment Kronenbourg a-t-elle transform\u00e9 une contrainte r\u00e9glementaire en un outil p\u00e9dagogique innovant gr\u00e2ce \u00e0 la visite virtuelle ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.virteem.fr\\\/\",\"name\":\"Virteem\",\"description\":\"Expert en visite virtuelle \u00e0 360\u00b0\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.virteem.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/#organization\",\"name\":\"Virteem\",\"url\":\"https:\\\/\\\/www.virteem.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.virteem.fr\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo-format-Horizontal-Aplat-couleur-sur-fond-clair.svg\",\"contentUrl\":\"https:\\\/\\\/www.virteem.fr\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Logo-format-Horizontal-Aplat-couleur-sur-fond-clair.svg\",\"width\":1366,\"height\":768,\"caption\":\"Virteem\"},\"image\":{\"@id\":\"https:\\\/\\\/www.virteem.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Etude de cas - Kronenbourg","description":"Kronenbourg mise sur une visite virtuelle immersive pour moderniser et renforcer la formation s\u00e9curit\u00e9 sur son site industriel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/","og_locale":"en_US","og_type":"article","og_title":"Etude de cas - Kronenbourg","og_description":"Kronenbourg mise sur une visite virtuelle immersive pour moderniser et renforcer la formation s\u00e9curit\u00e9 sur son site industriel.","og_url":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/","og_site_name":"Virteem","article_modified_time":"2025-09-08T15:16:23+00:00","og_image":[{"width":1024,"height":536,"url":"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-7-1024x536.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/","url":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/","name":"Etude de cas - Kronenbourg","isPartOf":{"@id":"https:\/\/www.virteem.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/#primaryimage"},"image":{"@id":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-7.png","datePublished":"2025-07-09T09:44:12+00:00","dateModified":"2025-09-08T15:16:23+00:00","description":"Kronenbourg mise sur une visite virtuelle immersive pour moderniser et renforcer la formation s\u00e9curit\u00e9 sur son site industriel.","breadcrumb":{"@id":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/#primaryimage","url":"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-7.png","contentUrl":"https:\/\/www.virteem.fr\/wp-content\/uploads\/2025\/07\/Vignette-Etude-de-cas-7.png","width":1797,"height":940,"caption":"Etude de cas - Brasseries Kronenbourg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.virteem.fr\/en\/portfolio\/comment-kronenbourg-a-t-elle-transforme-une-contrainte-reglementaire-en-un-outil-pedagogique-innovant-grace-a-la-visite-virtuelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.virteem.fr\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/www.virteem.fr\/en\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Comment Kronenbourg a-t-elle transform\u00e9 une contrainte r\u00e9glementaire en un outil p\u00e9dagogique innovant gr\u00e2ce \u00e0 la visite virtuelle ?"}]},{"@type":"WebSite","@id":"https:\/\/www.virteem.fr\/#website","url":"https:\/\/www.virteem.fr\/","name":"Virteem","description":"Expert en visite virtuelle \u00e0 360\u00b0","publisher":{"@id":"https:\/\/www.virteem.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.virteem.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.virteem.fr\/#organization","name":"Virteem","url":"https:\/\/www.virteem.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.virteem.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/Logo-format-Horizontal-Aplat-couleur-sur-fond-clair.svg","contentUrl":"https:\/\/www.virteem.fr\/wp-content\/uploads\/2022\/05\/Logo-format-Horizontal-Aplat-couleur-sur-fond-clair.svg","width":1366,"height":768,"caption":"Virteem"},"image":{"@id":"https:\/\/www.virteem.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/portfolio\/17127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/comments?post=17127"}],"version-history":[{"count":47,"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/portfolio\/17127\/revisions"}],"predecessor-version":[{"id":19944,"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/portfolio\/17127\/revisions\/19944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/media\/18916"}],"wp:attachment":[{"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/media?parent=17127"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/portfolio_category?post=17127"},{"taxonomy":"portfolio_field","embeddable":true,"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/portfolio_field?post=17127"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/www.virteem.fr\/en\/wp-json\/wp\/v2\/portfolio_tag?post=17127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}